{"id":18373,"date":"2024-08-19T11:03:35","date_gmt":"2024-08-19T08:03:35","guid":{"rendered":"https:\/\/alsalamahospital.com\/doctors\/internal-medicine\/anesthesia-pain-management\/%d8%b9%d8%a8%d8%af%d8%a7%d9%84%d9%84%d9%87-%d9%85%d8%ad%d9%85%d8%af-%d9%83%d8%b9%d9%83%d9%8a\/"},"modified":"2024-11-21T14:04:39","modified_gmt":"2024-11-21T11:04:39","slug":"abdullah-mohammed-kaki","status":"publish","type":"page","link":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/","title":{"rendered":"Professor Dr. Abdullah Mohammed Kaki"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">MB ChB (bachelor&#8217;s degree in general medicine, King Abdulaziz University)<br>FRCPC (Canadian fellowship in Anesthesia, university of Ottawa, Ontario, Canada)<br>Fellowship in pain management (university of Ottawa, Ontario, Canada)<br>Full professor in anesthesia, and pain management at the faculty of Medicine, King Abdulaziz University<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Professor of Pain Management Clinic<\/p>\n","protected":false},"author":35,"featured_media":13074,"parent":2442,"menu_order":20,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_angie_page":false,"footnotes":""},"categories":[],"tags":[],"page-author":[84],"class_list":["post-18373","page","type-page","status-publish","has-post-thumbnail","hentry","page-author-anesthesia-pain-management"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Professor Dr. Abdullah Mohammed Kaki - Al Salama Hospital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professor Dr. Abdullah Mohammed Kaki\" \/>\n<meta property=\"og:description\" content=\"Professor of Pain Management Clinic\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/\" \/>\n<meta property=\"og:site_name\" content=\"Al Salama Hospital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61554994652636\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-21T11:04:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/08\/Abdullah-Mohammed-Kaki.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1043\" \/>\n\t<meta property=\"og:image:height\" content=\"1156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Alsalamahosp\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/\",\"name\":\"Professor Dr. Abdullah Mohammed Kaki - Al Salama Hospital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Abdullah-Mohammed-Kaki.jpg\",\"datePublished\":\"2024-08-19T08:03:35+00:00\",\"dateModified\":\"2024-11-21T11:04:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Abdullah-Mohammed-Kaki.jpg\",\"contentUrl\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Abdullah-Mohammed-Kaki.jpg\",\"width\":1043,\"height\":1156},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/anesthesia-pain-management\\\/abdullah-mohammed-kaki\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctors\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Internal Medicine\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Anesthesia &#038; Pain Management\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/internal-medicine\\\/intensive-care-units-anesthesia\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Professor Dr. Abdullah Mohammed Kaki\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/\",\"name\":\"Al Salama Hospital - \u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#organization\"},\"alternateName\":\"\u0627\u0644\u0633\u0644\u0627\u0645\u0629\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#organization\",\"name\":\"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/alsalama-hospital.jpg\",\"contentUrl\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/alsalama-hospital.jpg\",\"width\":696,\"height\":696,\"caption\":\"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital\"},\"image\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61554994652636\",\"https:\\\/\\\/x.com\\\/Alsalamahosp\",\"https:\\\/\\\/www.instagram.com\\\/Alsalamahosp\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/al-salamahospital-sa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Professor Dr. Abdullah Mohammed Kaki - Al Salama Hospital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/","og_locale":"en_US","og_type":"article","og_title":"Professor Dr. Abdullah Mohammed Kaki","og_description":"Professor of Pain Management Clinic","og_url":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/","og_site_name":"Al Salama Hospital","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61554994652636","article_modified_time":"2024-11-21T11:04:39+00:00","og_image":[{"width":1043,"height":1156,"url":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/08\/Abdullah-Mohammed-Kaki.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Alsalamahosp","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/","url":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/","name":"Professor Dr. Abdullah Mohammed Kaki - Al Salama Hospital","isPartOf":{"@id":"https:\/\/alsalamahospital.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/#primaryimage"},"image":{"@id":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/#primaryimage"},"thumbnailUrl":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/08\/Abdullah-Mohammed-Kaki.jpg","datePublished":"2024-08-19T08:03:35+00:00","dateModified":"2024-11-21T11:04:39+00:00","breadcrumb":{"@id":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/#primaryimage","url":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/08\/Abdullah-Mohammed-Kaki.jpg","contentUrl":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/08\/Abdullah-Mohammed-Kaki.jpg","width":1043,"height":1156},{"@type":"BreadcrumbList","@id":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/anesthesia-pain-management\/abdullah-mohammed-kaki\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alsalamahospital.com\/en\/"},{"@type":"ListItem","position":2,"name":"Doctors","item":"https:\/\/alsalamahospital.com\/en\/doctors\/"},{"@type":"ListItem","position":3,"name":"Internal Medicine","item":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/"},{"@type":"ListItem","position":4,"name":"Anesthesia &#038; Pain Management","item":"https:\/\/alsalamahospital.com\/en\/doctors\/internal-medicine\/intensive-care-units-anesthesia\/"},{"@type":"ListItem","position":5,"name":"Professor Dr. Abdullah Mohammed Kaki"}]},{"@type":"WebSite","@id":"https:\/\/alsalamahospital.com\/en\/#website","url":"https:\/\/alsalamahospital.com\/en\/","name":"Al Salama Hospital - \u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629","description":"","publisher":{"@id":"https:\/\/alsalamahospital.com\/en\/#organization"},"alternateName":"\u0627\u0644\u0633\u0644\u0627\u0645\u0629","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alsalamahospital.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alsalamahospital.com\/en\/#organization","name":"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital","url":"https:\/\/alsalamahospital.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alsalamahospital.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/11\/alsalama-hospital.jpg","contentUrl":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/11\/alsalama-hospital.jpg","width":696,"height":696,"caption":"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital"},"image":{"@id":"https:\/\/alsalamahospital.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61554994652636","https:\/\/x.com\/Alsalamahosp","https:\/\/www.instagram.com\/Alsalamahosp\/","https:\/\/www.linkedin.com\/company\/al-salamahospital-sa\/"]}]}},"_links":{"self":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/18373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/comments?post=18373"}],"version-history":[{"count":1,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/18373\/revisions"}],"predecessor-version":[{"id":18375,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/18373\/revisions\/18375"}],"up":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/2442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/media\/13074"}],"wp:attachment":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/media?parent=18373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/categories?post=18373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/tags?post=18373"},{"taxonomy":"page-author","embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/page-author?post=18373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}