{"id":2976,"date":"2024-03-10T18:47:21","date_gmt":"2024-03-10T18:47:21","guid":{"rendered":"https:\/\/alsalamahospital.com\/doctors\/internal-medicine\/hamid-alsamadani\/"},"modified":"2026-04-19T15:57:51","modified_gmt":"2026-04-19T12:57:51","slug":"hamid-alsamadani","status":"publish","type":"page","link":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/","title":{"rendered":"Hamid Alsamadani"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bachelor of Medicine and Surgery, King Abdulaziz University<br>Jordanian Medical Council Certificate in Dermatology and Venereology<br>Master&#8217;s Degree in Clinical Dermatology, University of London<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consultant, Dermatology<\/p>\n","protected":false},"author":18,"featured_media":26266,"parent":6034,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"page-author":[],"class_list":["post-2976","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hamid Alsamadani - Al Salama Hospital<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hamid Alsamadani\" \/>\n<meta property=\"og:description\" content=\"Consultant, Dermatology\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/\" \/>\n<meta property=\"og:site_name\" content=\"Al Salama Hospital\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61554994652636\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-19T12:57:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2026\/04\/Hamed_samadani-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1043\" \/>\n\t<meta property=\"og:image:height\" content=\"1156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Alsalamahosp\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/\",\"name\":\"Hamid Alsamadani - Al Salama Hospital\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Hamed_samadani-1.webp\",\"datePublished\":\"2024-03-10T18:47:21+00:00\",\"dateModified\":\"2026-04-19T12:57:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Hamed_samadani-1.webp\",\"contentUrl\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Hamed_samadani-1.webp\",\"width\":1043,\"height\":1156},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/medical-facilities\\\/dermatology\\\/hamid-alsamadani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctors\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Medical Facilities\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/clinical-services\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dermatology\",\"item\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/doctors\\\/clinical-services\\\/dermatology\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Hamid Alsamadani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/\",\"name\":\"Al Salama Hospital - \u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#organization\"},\"alternateName\":\"\u0627\u0644\u0633\u0644\u0627\u0645\u0629\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#organization\",\"name\":\"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/alsalama-hospital.jpg\",\"contentUrl\":\"https:\\\/\\\/alsalamahospital.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/alsalama-hospital.jpg\",\"width\":696,\"height\":696,\"caption\":\"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital\"},\"image\":{\"@id\":\"https:\\\/\\\/alsalamahospital.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61554994652636\",\"https:\\\/\\\/x.com\\\/Alsalamahosp\",\"https:\\\/\\\/www.instagram.com\\\/Alsalamahosp\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/al-salamahospital-sa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hamid Alsamadani - Al Salama Hospital","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/","og_locale":"en_US","og_type":"article","og_title":"Hamid Alsamadani","og_description":"Consultant, Dermatology","og_url":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/","og_site_name":"Al Salama Hospital","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61554994652636","article_modified_time":"2026-04-19T12:57:51+00:00","og_image":[{"width":1043,"height":1156,"url":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2026\/04\/Hamed_samadani-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@Alsalamahosp","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/","url":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/","name":"Hamid Alsamadani - Al Salama Hospital","isPartOf":{"@id":"https:\/\/alsalamahospital.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/#primaryimage"},"image":{"@id":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/#primaryimage"},"thumbnailUrl":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2026\/04\/Hamed_samadani-1.webp","datePublished":"2024-03-10T18:47:21+00:00","dateModified":"2026-04-19T12:57:51+00:00","breadcrumb":{"@id":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/#primaryimage","url":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2026\/04\/Hamed_samadani-1.webp","contentUrl":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2026\/04\/Hamed_samadani-1.webp","width":1043,"height":1156},{"@type":"BreadcrumbList","@id":"https:\/\/alsalamahospital.com\/en\/doctors\/medical-facilities\/dermatology\/hamid-alsamadani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alsalamahospital.com\/en\/"},{"@type":"ListItem","position":2,"name":"Doctors","item":"https:\/\/alsalamahospital.com\/en\/doctors\/"},{"@type":"ListItem","position":3,"name":"Medical Facilities","item":"https:\/\/alsalamahospital.com\/en\/doctors\/clinical-services\/"},{"@type":"ListItem","position":4,"name":"Dermatology","item":"https:\/\/alsalamahospital.com\/en\/doctors\/clinical-services\/dermatology\/"},{"@type":"ListItem","position":5,"name":"Hamid Alsamadani"}]},{"@type":"WebSite","@id":"https:\/\/alsalamahospital.com\/en\/#website","url":"https:\/\/alsalamahospital.com\/en\/","name":"Al Salama Hospital - \u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629","description":"","publisher":{"@id":"https:\/\/alsalamahospital.com\/en\/#organization"},"alternateName":"\u0627\u0644\u0633\u0644\u0627\u0645\u0629","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alsalamahospital.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/alsalamahospital.com\/en\/#organization","name":"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital","url":"https:\/\/alsalamahospital.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/alsalamahospital.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/11\/alsalama-hospital.jpg","contentUrl":"https:\/\/alsalamahospital.com\/wp-content\/uploads\/2024\/11\/alsalama-hospital.jpg","width":696,"height":696,"caption":"\u0645\u0633\u062a\u0634\u0641\u0649 \u0627\u0644\u0633\u0644\u0627\u0645\u0629 - Al Salama Hospital"},"image":{"@id":"https:\/\/alsalamahospital.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61554994652636","https:\/\/x.com\/Alsalamahosp","https:\/\/www.instagram.com\/Alsalamahosp\/","https:\/\/www.linkedin.com\/company\/al-salamahospital-sa\/"]}]}},"_links":{"self":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/2976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/comments?post=2976"}],"version-history":[{"count":12,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/2976\/revisions"}],"predecessor-version":[{"id":22023,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/2976\/revisions\/22023"}],"up":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/pages\/6034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/media\/26266"}],"wp:attachment":[{"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/media?parent=2976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/categories?post=2976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/tags?post=2976"},{"taxonomy":"page-author","embeddable":true,"href":"https:\/\/alsalamahospital.com\/en\/wp-json\/wp\/v2\/page-author?post=2976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}